{"id":2585,"date":"2021-11-06T20:09:12","date_gmt":"2021-11-06T19:09:12","guid":{"rendered":"http:\/\/www.b4l-wien.at\/wp\/?p=2585"},"modified":"2021-11-06T20:09:12","modified_gmt":"2021-11-06T19:09:12","slug":"was-waere-wien-ohne-die-gruft","status":"publish","type":"post","link":"https:\/\/www.b4l-wien.at\/wp\/was-waere-wien-ohne-die-gruft\/","title":{"rendered":"Was w\u00e4re Wien ohne die Gruft?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.b4l-wien.at\/wp\/wp-content\/uploads\/2021\/11\/241822373_275024364456498_778520839869060933_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.b4l-wien.at\/wp\/wp-content\/uploads\/2021\/11\/241822373_275024364456498_778520839869060933_n.jpg\" alt=\"\" class=\"wp-image-2586\" srcset=\"https:\/\/www.b4l-wien.at\/wp\/wp-content\/uploads\/2021\/11\/241822373_275024364456498_778520839869060933_n.jpg 960w, https:\/\/www.b4l-wien.at\/wp\/wp-content\/uploads\/2021\/11\/241822373_275024364456498_778520839869060933_n-300x225.jpg 300w, https:\/\/www.b4l-wien.at\/wp\/wp-content\/uploads\/2021\/11\/241822373_275024364456498_778520839869060933_n-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><figcaption>Elli Brader, Judith Hartweger und Katharina Hladik<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-left\"><strong>Seit vielen Jahren ist die Gruft nun schon fester Bestandteil unserer Spendenpartnerschaften. Wir durften auch heuer die Gruft pers\u00f6nlich besuchen und haben im Gespr\u00e4ch mit Leiterin Judith Hartweger Spannendes \u00fcber das letzte Jahr erfahren d\u00fcrfen.<\/strong><\/p>\n\n\n\n<p>Die Gruft ist f\u00fcr viele Menschen eine Kostante, ein Ort, der ihnen Halt gibt. Das Tageszentrum ist gut besucht und bietet den Besucher*innen einen Raum der Ruhe und des Austauschs. Unsere Spende wird auch heuer wieder f\u00fcr den Kauf von Isomatten und Schlafs\u00e4cken genutzt, um wohnungslose Menschen zu unterst\u00fctzen, mit der K\u00e4lte zurecht zu kommen. Wir freuen uns umso mehr, dass mit den Jahren ein immer h\u00f6her werdender Betrag zusammenkommt. Dieses Jahr waren es 2633,60 Euro.  Leider reicht dieses Geld aber allein nicht aus, um gen\u00fcgend Isomatten und Schlafs\u00e4cke zur Verf\u00fcgung zu stellen. Au\u00dferdem werden auch andere Sachspenden ben\u00f6tigt. Die Gruft bittet um Herrenwinterschuhe sowie waschbare Wolldecken, die dringend ben\u00f6tigt werden. <\/p>\n\n\n\n<p>Eine Spendenabgabe ist rund um die Uhr m\u00f6glich: 7:30-21 Uhr in der Barnabitengasse 12a, 1060 Wien, bzw. von 21-7:30 Uhr unter der Mariahilfer Kirche. Danke f\u00fcr eure Spende.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit vielen Jahren ist die Gruft nun schon fester Bestandteil unserer Spendenpartnerschaften. Wir durften auch heuer die Gruft pers\u00f6nlich besuchen und haben im Gespr\u00e4ch mit Leiterin Judith Hartweger Spannendes \u00fcber das letzte Jahr erfahren d\u00fcrfen. Die Gruft ist f\u00fcr viele Menschen eine Kostante, ein Ort, der ihnen Halt gibt. Das Tageszentrum ist gut besucht und [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[153],"tags":[],"class_list":["post-2585","post","type-post","status-publish","format-standard","hentry","category-spenden"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/posts\/2585"}],"collection":[{"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/comments?post=2585"}],"version-history":[{"count":1,"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/posts\/2585\/revisions"}],"predecessor-version":[{"id":2587,"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/posts\/2585\/revisions\/2587"}],"wp:attachment":[{"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/media?parent=2585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/categories?post=2585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.b4l-wien.at\/wp\/wp-json\/wp\/v2\/tags?post=2585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}